{"id":40626,"date":"2024-09-05T16:08:01","date_gmt":"2024-09-05T14:08:01","guid":{"rendered":"https:\/\/sporttechs.it\/?post_type=product&#038;p=212117"},"modified":"2026-02-01T17:05:43","modified_gmt":"2026-02-01T16:05:43","slug":"outdoor-hose-herren-univers-softshell-u-tex-92336-copia-3","status":"publish","type":"product","link":"https:\/\/sporttechs.it\/de\/outdoor-hose-herren-univers-softshell-u-tex-92336-copia-3\/","title":{"rendered":"Outdoor-Hose Herren Univers Softshell U-TEX 92336"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Die Univers SoftShell U-Tex Herrenhose ist dank ihres ergonomischen Schnitts und der Elastizit\u00e4t des Softshell-Gewebes, aus dem sie hergestellt ist, ein \u00e4u\u00dferst bequemes Kleidungsst\u00fcck. Dank des Fleece-Futters und der wasserdichten U-Tex-Membran ist die Softshell U-Tex die perfekte Hose f\u00fcr Outdoor-Aktivit\u00e4ten in den Bergen, auch bei extremen Temperaturen und widrigen Wetterverh\u00e4ltnissen. Sie ist mit verschiedenen Taschen, einem elastischen Bund und einem Rei\u00dfverschluss am unteren Ende des Beins ausgestattet, um die Anpassung zu erleichtern. Das Kleidungsst\u00fcck ist in verschiedenen Farben mit kontrastierenden fluoreszierenden Eins\u00e4tzen und Prints erh\u00e4ltlich, die dem Kleidungsst\u00fcck einen \u00e4u\u00dferst modernen Look verleihen.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-weight: 400;\">Softshell Outdoor- und Trekkinghose, perfekt f\u00fcr die Herbst-Winter-Saison.<\/span>.<\/p>\n","protected":false},"featured_media":18234,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[523],"product_tag":[1737,1239,2837],"categoria_seo":[],"class_list":{"0":"post-40626","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-hosen","7":"product_tag-noadv-de","8":"product_tag-produkte50","9":"product_tag-rabatt-50","10":"pa_attivita-draussen","11":"pa_brand-univers-de","12":"pa_colore-blau-fluoreszierendes-orange","13":"pa_genere-mann","14":"pa_stagione-herbst-winter","15":"pa_taglia-3xl-de","16":"pa_taglia-l-de","17":"pa_taglia-m-de","18":"pa_taglia-s-de","19":"pa_taglia-xl-de","20":"pa_taglia-xxl-de","21":"pa_tessuto-softshell-de","23":"first","24":"instock","25":"sale","26":"purchasable","27":"product-type-variable","28":"has-default-attributes"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sporttechs.it\/de\/wp-json\/wp\/v2\/product\/40626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sporttechs.it\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sporttechs.it\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/de\/wp-json\/wp\/v2\/comments?post=40626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/de\/wp-json\/wp\/v2\/media\/18234"}],"wp:attachment":[{"href":"https:\/\/sporttechs.it\/de\/wp-json\/wp\/v2\/media?parent=40626"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sporttechs.it\/de\/wp-json\/wp\/v2\/product_brand?post=40626"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sporttechs.it\/de\/wp-json\/wp\/v2\/product_cat?post=40626"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sporttechs.it\/de\/wp-json\/wp\/v2\/product_tag?post=40626"},{"taxonomy":"categoria_seo","embeddable":true,"href":"https:\/\/sporttechs.it\/de\/wp-json\/wp\/v2\/categoria_seo?post=40626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}