{"id":259349,"date":"2024-08-26T15:58:37","date_gmt":"2024-08-26T13:58:37","guid":{"rendered":"https:\/\/sporttechs.it\/mochila-de-caza-nature-suede-4510-pf\/"},"modified":"2024-08-26T15:58:37","modified_gmt":"2024-08-26T13:58:37","slug":"mochila-de-caza-nature-suede-4510-pf","status":"publish","type":"product","link":"https:\/\/sporttechs.it\/es\/mochila-de-caza-nature-suede-4510-pf\/","title":{"rendered":"Mochila de caza Nature SUEDE 45+10 PF"},"content":{"rendered":"<p>Mochila de caza SUEDE 45+10 PF, t\u00e9cnica y silenciosa en material SUEDE con respaldo <a href=\"https:\/\/www.marsupio.it\/it\/nature_sistemi\/\" target=\"_blank\" rel=\"noopener\"><strong>SISTEMA 418X<\/strong><\/a> de malla transpirable. Dispone de correas acolchadas y ajustables para los hombros, con una correa para el pecho con hebilla deslizante y una correa envolvente para la cintura. El nuevo sistema de apertura de velcro permite acceder r\u00e1pidamente a la mochila sin hacer ruido. Dispone de 2 c\u00f3modos fuelles laterales para ampliar el volumen de la mochila en 10 litros; los fuelles se abren mediante cremallera y velcro. El bolsillo frontal oculto para rifle y carabina, \u00fatil para viajar con seguridad y comodidad, tiene en su interior un calcet\u00edn acolchado para la culata del rifle, que puede utilizarse como portaprendas enganch\u00e1ndolo a las hebillas exteriores. Cerrando la cremallera inferior, se convierte en un compartimento pr\u00e1ctico y espacioso. Dispone de un bolsillo frontal para llevar objetos con enganches funcionales, 2 pr\u00e1cticos bolsillos laterales acolchados en la parte inferior y un bolsillo en la capucha con impresi\u00f3n SOS. Tiene una bolsa interior termosellada, extra\u00edble y lavable. Funda de mochila insertada en la parte inferior.       <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mochila de caza con tirantes ajustables. Silenciosa con bolsillo para rifle o carabina. <\/p>\n","protected":false},"featured_media":259351,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1844],"product_tag":[],"categoria_seo":[],"class_list":{"0":"post-259349","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-mochilas-y-mochilas","7":"pa_attivita-caza","8":"pa_brand-naturaleza","9":"pa_colore-verde-es","10":"pa_genere-hombre","11":"pa_stagione-otono-invierno","12":"pa_taglia-una","13":"pa_tessuto-ante","15":"first","16":"instock","17":"purchasable","18":"product-type-variable","19":"has-default-attributes"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/product\/259349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/comments?post=259349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/media\/259351"}],"wp:attachment":[{"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/media?parent=259349"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/product_brand?post=259349"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/product_cat?post=259349"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/product_tag?post=259349"},{"taxonomy":"categoria_seo","embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/categoria_seo?post=259349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}