{"id":263849,"date":"2023-08-21T07:12:19","date_gmt":"2023-08-21T05:12:19","guid":{"rendered":"https:\/\/sporttechs.it\/tunica-de-caza-para-hombre-univers-microfibra-93081-2\/"},"modified":"2025-11-11T00:23:15","modified_gmt":"2025-11-10T23:23:15","slug":"tunica-de-caza-para-hombre-univers-microfibra-93081-2","status":"publish","type":"product","link":"https:\/\/sporttechs.it\/es\/tunica-de-caza-para-hombre-univers-microfibra-93081-2\/","title":{"rendered":"T\u00fanica de caza para hombre Univers MICROFIBRA 93081"},"content":{"rendered":"<p>El chaleco de caza de microfibra Univers es una prenda esencial para el cazador. Cuidadosamente confeccionado en suave y silenciosa microfibra laminada con membrana U-Tex, garantiza altos niveles de comodidad y practicidad. Con diversos bolsillos externos e internos, ofrece espacio suficiente para organizar y transportar todos los objetos necesarios durante la actividad cineg\u00e9tica. Adem\u00e1s, el amplio bolsillo trasero facilita la limpieza y el mantenimiento.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00fanica de caza de microfibra silenciosa, perfecta para la temporada de oto\u00f1o-invierno.<\/p>\n","protected":false},"featured_media":263851,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1822],"product_tag":[],"categoria_seo":[],"class_list":{"0":"post-263849","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chalecos","7":"pa_attivita-caza","8":"pa_brand-univers-es","9":"pa_colore-verde-es","10":"pa_colore-verde-naranja-fluorescente","11":"pa_genere-hombre","12":"pa_stagione-otono-invierno","13":"pa_taglia-3xl-es","14":"pa_taglia-l-es","15":"pa_taglia-m-es","16":"pa_taglia-s-es","17":"pa_taglia-xl-es","18":"pa_taglia-xxl-es","19":"pa_tessuto-microfibra-es","21":"first","22":"instock","23":"purchasable","24":"product-type-variable","25":"has-default-attributes"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/product\/263849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/comments?post=263849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/media\/263851"}],"wp:attachment":[{"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/media?parent=263849"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/product_brand?post=263849"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/product_cat?post=263849"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/product_tag?post=263849"},{"taxonomy":"categoria_seo","embeddable":true,"href":"https:\/\/sporttechs.it\/es\/wp-json\/wp\/v2\/categoria_seo?post=263849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}