{"id":59453,"date":"2023-10-03T15:59:11","date_gmt":"2023-10-03T13:59:11","guid":{"rendered":"https:\/\/sporttechs.it\/veste-de-chasse-homme-univers-rovo-cordura-u-tex-91103\/"},"modified":"2026-06-20T16:34:11","modified_gmt":"2026-06-20T14:34:11","slug":"veste-de-chasse-homme-univers-rovo-cordura-u-tex-91103","status":"publish","type":"product","link":"https:\/\/sporttechs.it\/fr\/veste-de-chasse-homme-univers-rovo-cordura-u-tex-91103\/","title":{"rendered":"Veste de chasse Homme Univers ROVO CORDURA\u00ae U-TEX 91103"},"content":{"rendered":"<p>La veste de chasse ROVO CORDURA\u00ae U-TEX d&#8217;Univers est con\u00e7ue pour les chasseurs souhaitant s&#8217;aventurer sur des terrains inaccessibles et bois\u00e9s. Elle est fabriqu\u00e9e en oxford 100 % polyester, une mati\u00e8re r\u00e9put\u00e9e pour sa r\u00e9sistance et sa durabilit\u00e9. La membrane U-TEX rend la veste imperm\u00e9able et respirante, r\u00e9sistante \u00e0 la pluie et aux intemp\u00e9ries. Les manches en Cordura\u00ae r\u00e9sistant \u00e0 la d\u00e9chirure offrent une protection suppl\u00e9mentaire contre les ronces, les branches et autres \u00e9l\u00e9ments naturels qui pourraient ab\u00eemer le tissu. Elle est \u00e9quip\u00e9e d&#8217;une poche satellite, d&#8217;un sac \u00e0 gibier arri\u00e8re, d&#8217;une poche int\u00e9rieure et d&#8217;une capuche amovible.    <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veste de chasse avec manches en Cordura\u00ae et poche satellite, parfaite pour la saison froide.<\/p>\n","protected":false},"featured_media":59454,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1331],"product_tag":[],"categoria_seo":[],"class_list":{"0":"post-59453","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vestes","7":"pa_attivita-chasse","8":"pa_brand-univers-fr","9":"pa_colore-vert-orange-fluorescent","10":"pa_genere-lhomme","11":"pa_stagione-automne-hiver","12":"pa_taglia-46-fr","13":"pa_taglia-48-fr","14":"pa_taglia-50-fr","15":"pa_taglia-52-fr","16":"pa_taglia-54-fr","17":"pa_taglia-56-fr","18":"pa_taglia-58-fr","19":"pa_taglia-60-fr","20":"pa_taglia-62-fr","21":"pa_tessuto-technicien","23":"first","24":"instock","25":"sale","26":"purchasable","27":"product-type-variable","28":"has-default-attributes"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product\/59453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/comments?post=59453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/media\/59454"}],"wp:attachment":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/media?parent=59453"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product_brand?post=59453"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product_cat?post=59453"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product_tag?post=59453"},{"taxonomy":"categoria_seo","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/categoria_seo?post=59453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}