{"id":62968,"date":"2024-07-15T15:14:25","date_gmt":"2024-07-15T13:14:25","guid":{"rendered":"https:\/\/sporttechs.it\/sac-a-dos-de-chasse-homme-nature-forest-25-forestom025\/"},"modified":"2024-07-15T15:14:25","modified_gmt":"2024-07-15T13:14:25","slug":"sac-a-dos-de-chasse-homme-nature-forest-25-forestom025","status":"publish","type":"product","link":"https:\/\/sporttechs.it\/fr\/sac-a-dos-de-chasse-homme-nature-forest-25-forestom025\/","title":{"rendered":"Sac \u00e0 dos de chasse Homme Nature FOREST 25 FORESTOM025"},"content":{"rendered":"<p>Sac \u00e0 dos de chasse FOREST 25, tr\u00e8s fonctionnel pour la chasse au petit gibier. Le nouveau syst\u00e8me d&#8217;ouverture HOOKS permet d&#8217;acc\u00e9der rapidement au sac \u00e0 dos sans faire de bruit. Il est \u00e9quip\u00e9 du syst\u00e8me U SYSTEM, de bretelles rembourr\u00e9es et r\u00e9glables en mesh respirant, d&#8217;une sangle de poitrine avec boucle et d&#8217;une sangle de taille enveloppante en mesh. Il est \u00e9quip\u00e9 de nombreuses poches : une poche cartouche sur la ceinture, une poche lat\u00e9rale en filet pour la bouteille d&#8217;eau, une poche sur la capuche avec impression interne SOS, une grande poche frontale et une poche rembourr\u00e9e sur le c\u00f4t\u00e9 gauche pour le spektiv. La fermeture \u00e9clair lat\u00e9rale qui coupe le sac \u00e0 dos verticalement est utile pour acc\u00e9der rapidement \u00e0 l&#8217;int\u00e9rieur. Enfin, il est \u00e9quip\u00e9 de sangles de compression des deux c\u00f4t\u00e9s et d&#8217;une housse de sac \u00e0 dos ins\u00e9r\u00e9e au fond.     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sac \u00e0 dos de chasse camoufl\u00e9e, pour le petit gibier.<\/p>\n","protected":false},"featured_media":62969,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1464],"product_tag":[],"categoria_seo":[],"class_list":{"0":"post-62968","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sacs-a-dos-et-sacs-a-dos","7":"pa_attivita-chasse","8":"pa_brand-nature-fr","9":"pa_colore-vert","10":"pa_genere-lhomme","11":"pa_stagione-automne-hiver","12":"pa_taglia-un","13":"pa_tessuto-technicien","15":"first","16":"instock","17":"purchasable","18":"product-type-variable","19":"has-default-attributes"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product\/62968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/comments?post=62968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/media\/62969"}],"wp:attachment":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/media?parent=62968"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product_brand?post=62968"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product_cat?post=62968"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product_tag?post=62968"},{"taxonomy":"categoria_seo","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/categoria_seo?post=62968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}