{"id":62986,"date":"2024-07-15T15:49:55","date_gmt":"2024-07-15T13:49:55","guid":{"rendered":"https:\/\/sporttechs.it\/gilet-de-chasse-homme-univers-roccastrada-93177-2\/"},"modified":"2026-07-03T00:39:06","modified_gmt":"2026-07-02T22:39:06","slug":"gilet-de-chasse-homme-univers-roccastrada-93177-2","status":"publish","type":"product","link":"https:\/\/sporttechs.it\/fr\/gilet-de-chasse-homme-univers-roccastrada-93177-2\/","title":{"rendered":"Gilet de chasse homme Univers ROCCASTRADA 93177"},"content":{"rendered":"<p>Gilet de chasse ROCCASTRADA en toile de coton m\u00e9lang\u00e9 r\u00e9sistante avec applications de tissu RK-TEX et parties en vert fluorescent pour une meilleure visibilit\u00e9 dans toutes les conditions. Deux grandes poches frontales, deux poches \u00e0 soufflet avec rabat, une poche zipp\u00e9e et une grande poche \u00e0 soufflet d\u00e9tachable. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gilet de chasse en toile avec poches \u00e0 soufflet sur le devant.<\/p>\n","protected":false},"featured_media":62987,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1368],"product_tag":[],"categoria_seo":[],"class_list":{"0":"post-62986","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gilets","7":"pa_attivita-chasse","8":"pa_brand-univers-fr","9":"pa_colore-vert-vert-fluorescent","10":"pa_genere-lhomme","11":"pa_stagione-printemps-ete","12":"pa_taglia-46-fr","13":"pa_taglia-48-fr","14":"pa_taglia-50-fr","15":"pa_taglia-52-fr","16":"pa_taglia-54-fr","17":"pa_taglia-56-fr","18":"pa_taglia-58-fr","19":"pa_taglia-60-fr","20":"pa_tessuto-technicien","22":"first","23":"instock","24":"purchasable","25":"product-type-variable","26":"has-default-attributes"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product\/62986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/comments?post=62986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/media\/62987"}],"wp:attachment":[{"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/media?parent=62986"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product_brand?post=62986"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product_cat?post=62986"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/product_tag?post=62986"},{"taxonomy":"categoria_seo","embeddable":true,"href":"https:\/\/sporttechs.it\/fr\/wp-json\/wp\/v2\/categoria_seo?post=62986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}